{"id":46230,"date":"2024-10-27T02:48:55","date_gmt":"2024-10-27T02:48:55","guid":{"rendered":"https:\/\/cartoleriadonati.ch\/prodotto\/personalisierte-tasse-sternzeichen\/"},"modified":"2026-05-03T12:37:59","modified_gmt":"2026-05-03T12:37:59","slug":"personalisierte-tasse-sternzeichen","status":"publish","type":"product","link":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/","title":{"rendered":"Personalisierte Tasse Sternzeichen"},"content":{"rendered":"<p>Die personalisierte Tasse Sternzeichen ist das perfekte Geschenk f\u00fcr alle, die t\u00e4glich ein Symbol ihres Sternzeichens bei sich tragen m\u00f6chten. Hergestellt aus hochwertiger Keramik, vereint diese Tasse Funktionalit\u00e4t und Stil und wird zu einem einzigartigen Accessoire, das die Pers\u00f6nlichkeit des Nutzers widerspiegelt. Dank der Personalisierungsm\u00f6glichkeiten k\u00f6nnen Sie sie wirklich besonders gestalten, indem Sie aus einer Vielzahl von Optionen w\u00e4hlen, um sie an den Geschmack und Stil des Beschenkten anzupassen.  <\/p>\n<p><strong>Umfangreiche Personalisierungsoptionen<\/strong><\/p>\n<p>Die Tasse ist vollst\u00e4ndig personalisierbar: Sie k\u00f6nnen das gew\u00fcnschte Sternzeichen-Symbol ausw\u00e4hlen und Farbe sowie Gr\u00f6\u00dfe des Symbols \u00e4ndern. Dies erm\u00f6glicht es, das Design an die pers\u00f6nlichen Vorlieben anzupassen und macht sie perfekt sowohl f\u00fcr diejenigen, die einen dezenten Stil bevorzugen, als auch f\u00fcr diejenigen, die ein auff\u00e4lligeres Design m\u00f6gen. Auf der gegen\u00fcberliegenden Seite k\u00f6nnen Sie einen Text, einen Namen oder eine besondere Widmung hinzuf\u00fcgen, um das Geschenk noch pers\u00f6nlicher und bedeutungsvoller zu gestalten. Alternativ k\u00f6nnen Sie f\u00fcr eine noch pers\u00f6nlichere Note ein Foto oder ein Bild hochladen, das in hoher Aufl\u00f6sung gedruckt wird. Die Vielfalt der Personalisierungsoptionen macht diese Tasse f\u00fcr alle Altersgruppen und jeden Anlass geeignet.    <\/p>\n<p><strong>Qualit\u00e4t und Langlebigkeit<\/strong><\/p>\n<p>Diese Keramiktasse ist f\u00fcr den t\u00e4glichen Gebrauch konzipiert. Sie ist hitzebest\u00e4ndig und sowohl mikrowellen- als auch sp\u00fclmaschinengeeignet, was Funktionalit\u00e4t und Langlebigkeit garantiert. Der Druck wird mit einer fortschrittlichen Technologie realisiert, die lebendige Farben und scharfe Details gew\u00e4hrleistet, die h\u00e4ufigem Waschen standhalten. Das Fassungsverm\u00f6gen der Tasse ist ideal zum Genie\u00dfen von hei\u00dfen Getr\u00e4nken wie Kaffee, Tee oder Schokolade, kann aber auch f\u00fcr kalte Getr\u00e4nke verwendet werden. Dar\u00fcber hinaus machen der komfortable Griff und das ergonomische Design sie leicht handhabbar.    <\/p>\n<p><strong>Ein einzigartiges und bedeutungsvolles Geschenk<\/strong><\/p>\n<p>Diese personalisierte Tasse mit Sternzeichen ist viel mehr als nur ein einfaches Accessoire: Sie stellt ein einzigartiges und besonderes Geschenk f\u00fcr den Beschenkten dar. Sie ist perfekt als Geschenk f\u00fcr Geburtstage, Weihnachten, Valentinstag oder andere besondere Anl\u00e4sse, bei denen man etwas schenken m\u00f6chte, das die Pers\u00f6nlichkeit des Beschenkten widerspiegelt. Durch die Wahl des Sternzeichens f\u00fcgen Sie eine pers\u00f6nliche Note hinzu, die Aufmerksamkeit und Kenntnis der anderen Person zeigt und diesen Gegenstand zu einer wertvollen Erinnerung macht.  <\/p>\n<p>Mit der M\u00f6glichkeit, auch eine Widmung oder ein Foto hinzuzuf\u00fcgen, wird diese Tasse zu einem wahren Symbol der Zuneigung und des Teilens. Direkt online in wenigen einfachen Schritten personalisierbar, ist sie ein originelles und vielseitiges Geschenk, perfekt f\u00fcr alle, die mit einem Gegenstand \u00fcberraschen m\u00f6chten, der Emotion und Bedeutung vereint. <\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"ai-optimize-21 ai-optimize-introduction\">[fpd_module type=\"designs\"]<br \/>\n[fpd_module type=\"text\"]<br \/>\n[fpd_module type=\"images\"]<\/p>\n","protected":false},"featured_media":46236,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-46230","product","type-product","status-publish","has-post-thumbnail","product_cat-uncategorized","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Personalisierte Tasse Sternzeichen - Cartoleria Donati SA<\/title>\n<meta name=\"description\" content=\"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personalisierte Tasse Sternzeichen\" \/>\n<meta property=\"og:description\" content=\"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/\" \/>\n<meta property=\"og:site_name\" content=\"Cartoleria Donati SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CartoleriaDonati\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T12:37:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2024\/10\/Foto-prodotto-sito-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#067;&#072;&#070;19.90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/\",\"url\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/\",\"name\":\"Personalisierte Tasse Sternzeichen - Cartoleria Donati SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cartoleriadonati.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Foto-prodotto-sito-11.jpg\",\"datePublished\":\"2024-10-27T02:48:55+00:00\",\"dateModified\":\"2026-05-03T12:37:59+00:00\",\"description\":\"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cartoleriadonati.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Foto-prodotto-sito-11.jpg\",\"contentUrl\":\"https:\\\/\\\/cartoleriadonati.ch\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Foto-prodotto-sito-11.jpg\",\"width\":1200,\"height\":1500,\"caption\":\"Personalisierte Tasse Sternzeichen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Personalisierte Tasse Sternzeichen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/\",\"name\":\"Cartoleria Donati SA\",\"description\":\"Sito internet ufficiale della Cartoleria Donati SA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\",\"Store\"],\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/#organization\",\"name\":\"Cartoleria Donati SA\",\"url\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CartoleriaDonati\"],\"address\":{\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#local-main-place-address\"},\"telephone\":[\"0798516188\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"0798516188\",\"email\":\"patrick.donati@hotmail.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@cartoleriadonati.ch\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#local-main-place-address\",\"streetAddress\":\"Via Locarno 32\",\"addressLocality\":\"Losone\",\"postalCode\":\"6616\",\"addressRegion\":\"Ticino\",\"addressCountry\":\"CH\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cartoleriadonati.ch\\\/de\\\/prodotto\\\/personalisierte-tasse-sternzeichen\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/cartoleriadonati.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/DONATI_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/cartoleriadonati.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/DONATI_logo-1.png\",\"width\":2339,\"height\":1654,\"caption\":\"Cartoleria Donati SA\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"CHF\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Losone\" \/>\n<meta name=\"geo.region\" content=\"Schweiz\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Personalisierte Tasse Sternzeichen - Cartoleria Donati SA","description":"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/","og_locale":"de_DE","og_type":"article","og_title":"Personalisierte Tasse Sternzeichen","og_description":"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.","og_url":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/","og_site_name":"Cartoleria Donati SA","article_publisher":"https:\/\/www.facebook.com\/CartoleriaDonati","article_modified_time":"2026-05-03T12:37:59+00:00","og_image":[{"width":1200,"height":1500,"url":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2024\/10\/Foto-prodotto-sito-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&#67;&#72;&#70;19.90","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/","url":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/","name":"Personalisierte Tasse Sternzeichen - Cartoleria Donati SA","isPartOf":{"@id":"https:\/\/cartoleriadonati.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#primaryimage"},"image":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#primaryimage"},"thumbnailUrl":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2024\/10\/Foto-prodotto-sito-11.jpg","datePublished":"2024-10-27T02:48:55+00:00","dateModified":"2026-05-03T12:37:59+00:00","description":"Personalisierte Tasse Sternzeichen, Personalisieren Sie die Tasse mit Ihrem bevorzugten Sternzeichen und f\u00fcgen Sie auch Text und Fotos hinzu.","breadcrumb":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#primaryimage","url":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2024\/10\/Foto-prodotto-sito-11.jpg","contentUrl":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2024\/10\/Foto-prodotto-sito-11.jpg","width":1200,"height":1500,"caption":"Personalisierte Tasse Sternzeichen"},{"@type":"BreadcrumbList","@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cartoleriadonati.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/cartoleriadonati.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Personalisierte Tasse Sternzeichen"}]},{"@type":"WebSite","@id":"https:\/\/cartoleriadonati.ch\/de\/#website","url":"https:\/\/cartoleriadonati.ch\/de\/","name":"Cartoleria Donati SA","description":"Sito internet ufficiale della Cartoleria Donati SA","publisher":{"@id":"https:\/\/cartoleriadonati.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cartoleriadonati.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place","Store"],"@id":"https:\/\/cartoleriadonati.ch\/de\/#organization","name":"Cartoleria Donati SA","url":"https:\/\/cartoleriadonati.ch\/de\/","logo":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#local-main-organization-logo"},"image":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/CartoleriaDonati"],"address":{"@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#local-main-place-address"},"telephone":["0798516188"],"contactPoint":{"@type":"ContactPoint","telephone":"0798516188","email":"patrick.donati@hotmail.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@cartoleriadonati.ch"},{"@type":"PostalAddress","@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#local-main-place-address","streetAddress":"Via Locarno 32","addressLocality":"Losone","postalCode":"6616","addressRegion":"Ticino","addressCountry":"CH"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cartoleriadonati.ch\/de\/prodotto\/personalisierte-tasse-sternzeichen\/#local-main-organization-logo","url":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2019\/06\/DONATI_logo-1.png","contentUrl":"https:\/\/cartoleriadonati.ch\/wp-content\/uploads\/2019\/06\/DONATI_logo-1.png","width":2339,"height":1654,"caption":"Cartoleria Donati SA"}]},"product_price_amount":"19.90","product_price_currency":"CHF","og_availability":"instock","product_availability":"instock","product_condition":"new","geo.placename":"Losone","geo.region":"Schweiz"},"_links":{"self":[{"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/product\/46230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/media\/46236"}],"wp:attachment":[{"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/media?parent=46230"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/product_brand?post=46230"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/product_cat?post=46230"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cartoleriadonati.ch\/de\/wp-json\/wp\/v2\/product_tag?post=46230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}